{"id":664,"date":"2015-12-13T19:19:32","date_gmt":"2015-12-13T18:19:32","guid":{"rendered":"http:\/\/www.soscasa-onlus.it\/soscasa\/?p=664"},"modified":"2016-02-16T19:34:29","modified_gmt":"2016-02-16T18:34:29","slug":"case-sfitte-deuropa","status":"publish","type":"post","link":"https:\/\/www.soscasa-onlus.it\/soscasa\/2015\/12\/13\/case-sfitte-deuropa\/","title":{"rendered":"CASE SFITTE D&#8217;EUROPA"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.soscasa-onlus.it\/soscasa\/wp-content\/uploads\/2016\/02\/eurostat.jpg\" rel=\"attachment wp-att-665\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-665\" src=\"http:\/\/www.soscasa-onlus.it\/soscasa\/wp-content\/uploads\/2016\/02\/eurostat-300x211.jpg\" alt=\"eurostat\" width=\"300\" height=\"211\" srcset=\"https:\/\/www.soscasa-onlus.it\/soscasa\/wp-content\/uploads\/2016\/02\/eurostat-300x211.jpg 300w, https:\/\/www.soscasa-onlus.it\/soscasa\/wp-content\/uploads\/2016\/02\/eurostat-768x541.jpg 768w, https:\/\/www.soscasa-onlus.it\/soscasa\/wp-content\/uploads\/2016\/02\/eurostat-1024x722.jpg 1024w, https:\/\/www.soscasa-onlus.it\/soscasa\/wp-content\/uploads\/2016\/02\/eurostat.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Eurostat, l\u2019agenzia di statistiche della Ue \u00e8 il primo grande ente statistico che analizza il patrimonio costruito dal punto di vista del \u201cvuoto\u201d. In uno studio appena ultimato definisce quantit\u00e0 e qualit\u00e0 del patrimonio residenziale che risulta sfitto o sottoutilizzato. Ne racconta Enrico Franceschini su La Repubblica del 12 dicembre 2015 con l\u2019articolo Europa, record di case sfitte e una su tre \u00e8 abitata da single (di cui si riporta anche l\u2019immagine collegata all\u2019articolo).<\/p>\n<p style=\"text-align: justify;\">Si evidenza cos\u00ec come \u201cmolti alloggi sono disabitati, molti europei vivono soli, la maggioranza delle case ha pi\u00f9 di settant\u2019anni e forse bisogno di un restauro\u201d e ancora \u201cun\u2019abitazione su sei, in Europa, \u00e8 disabitata. Il record va al Sud: spesso sono alloggi per le vacanze\u201d. Una ricerca che segna certamente un\u2019inversione di tendenza nei riguardi del tema degli spazi vuoti, ma che al tempo stesso segna il ritardo di politiche organiche che puntino pi\u00f9 decisamente ad un mix di interventi tra rigenerazione, rammendo e agopuntura con sempre maggior attenzione alla dimensione sociale dei problemi. E\u2019 davvero tempo di riformare l\u2019urbanistica alla radice, probabilmente ricomprendendo anche il suggerimento del libro \u201cContro l\u2019Urbanistica\u201d di Franco La Cecla quando rivendica l\u2019urgenza di una \u201cvalutazione di impatto sociale\u201d (Vis) delle pianificazioni urbane, raccomandata dalla Commissione Europea ma molto di l\u00e0 da venire in Italia.<\/p>\n<p>Roberto Tognetti<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eurostat, l\u2019agenzia di statistiche della Ue \u00e8 il primo grande ente statistico che analizza il patrimonio costruito dal punto di vista del \u201cvuoto\u201d. In uno studio appena ultimato definisce quantit\u00e0 e qualit\u00e0 del patrimonio residenziale che risulta sfitto o sottoutilizzato. Ne racconta Enrico Franceschini su La Repubblica del 12 dicembre 2015 con l\u2019articolo Europa, record&#8230;<\/p>\n","protected":false},"author":1,"featured_media":665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[11],"tags":[],"acf":[],"views":880,"_links":{"self":[{"href":"https:\/\/www.soscasa-onlus.it\/soscasa\/wp-json\/wp\/v2\/posts\/664"}],"collection":[{"href":"https:\/\/www.soscasa-onlus.it\/soscasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.soscasa-onlus.it\/soscasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.soscasa-onlus.it\/soscasa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soscasa-onlus.it\/soscasa\/wp-json\/wp\/v2\/comments?post=664"}],"version-history":[{"count":3,"href":"https:\/\/www.soscasa-onlus.it\/soscasa\/wp-json\/wp\/v2\/posts\/664\/revisions"}],"predecessor-version":[{"id":668,"href":"https:\/\/www.soscasa-onlus.it\/soscasa\/wp-json\/wp\/v2\/posts\/664\/revisions\/668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soscasa-onlus.it\/soscasa\/wp-json\/wp\/v2\/media\/665"}],"wp:attachment":[{"href":"https:\/\/www.soscasa-onlus.it\/soscasa\/wp-json\/wp\/v2\/media?parent=664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soscasa-onlus.it\/soscasa\/wp-json\/wp\/v2\/categories?post=664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soscasa-onlus.it\/soscasa\/wp-json\/wp\/v2\/tags?post=664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}